{"id":9091,"date":"2021-04-28T09:25:01","date_gmt":"2021-04-28T07:25:01","guid":{"rendered":"https:\/\/nodengo.com\/?post_type=citadela-item&#038;p=9091"},"modified":"2023-10-15T13:51:07","modified_gmt":"2023-10-15T11:51:07","slug":"fork-and-bottle","status":"publish","type":"citadela-item","link":"https:\/\/nodengo.com\/pt\/item\/fork-and-bottle\/","title":{"rendered":"Fork &#038; Bottle"},"content":{"rendered":"<p><img decoding=\"async\" data-src=\"https:\/\/nodengo.com\/wp-content\/uploads\/bbjlogo22.gif\" alt=\"Fork &#038; Bottle\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 58px; --smush-placeholder-aspect-ratio: 58\/57;\">\u00a0 <\/p>\n<h4>Fork &#038; Bottle<\/h4>\n<\/p>\n<p>Today, Fork &#038; Bottle is known for being the only farm-to-table restaurant in Zurich offering an ever-changing selection of more than 60 craft beers and one of the biggest beer gardens in the city.<br \/>\nO menu de comida sazonal, inspirado em nossas origens internacionais, oferece comida caseira caseira e sofisticada, criada de forma criativa por nossos chefs. Trabalhando diretamente com os agricultores locais, podemos servir comida deliciosa a um pre\u00e7o justo.<\/p>\n<p>Temos orgulho de ter um servi\u00e7o amig\u00e1vel e flex\u00edvel. O restaurante tamb\u00e9m \u00e9 extremamente acolhedor para as fam\u00edlias, com um menu infantil dedicado, uma grande sala de jogos interna e uma \u00e1rea de recrea\u00e7\u00e3o infantil ao ar livre cercada.<\/p>\n<p>Por meio de um menu de brunch de fim de semana de destaque, alimentos e bebidas locais e um calend\u00e1rio cont\u00ednuo de eventos, a Fork &amp; Bottle criou uma comunidade \u00fanica. Localizada em um ambiente campestre descontra\u00eddo nos arredores de Zurique, aspiramos criar um lugar acolhedor para que todos possam desfrutar!<\/p>\n<p><i class=\"fas fa-utensils\"><\/i><a href=\"https:\/\/nodengo.com\/pt\/zurich\/zurich-restaurants\/\">OUTROS RESTAURANTES EM ZURIQUE<\/a> <\/p>","protected":false},"excerpt":{"rendered":"<p>Fork &#038; Bottle was born in 2012 from a love of craft beer, gastro-pub cuisine, and community.<\/p>","protected":false},"author":249,"featured_media":9092,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","citadela-item-category":[467,334],"citadela-item-location":[390],"class_list":["post-9091","citadela-item","type-citadela-item","status-publish","has-post-thumbnail","hentry","citadela-item-category-gastropub","citadela-item-category-restaurant","citadela-item-location-zurich"],"uagb_featured_image_src":{"full":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich.jpg",507,321,false],"thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich-150x150.jpg",150,150,true],"medium":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich-300x190.jpg",300,190,true],"medium_large":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich.jpg",507,321,false],"large":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich.jpg",507,321,false],"1536x1536":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich.jpg",507,321,false],"2048x2048":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich.jpg",507,321,false],"trp-custom-language-flag":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich-16x10.jpg",16,10,true],"citadela_item_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich.jpg",507,321,false],"woocommerce_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich.jpg",507,321,false],"woocommerce_single":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich.jpg",507,321,false],"woocommerce_gallery_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich-150x95.jpg",150,95,true],"citadela_service":["https:\/\/nodengo.com\/wp-content\/uploads\/fork-bottle-zurich-480x321.jpg",480,321,true]},"uagb_author_info":{"display_name":"Team Nodengo","author_link":"https:\/\/nodengo.com\/pt\/author\/nodengo-team\/"},"uagb_comment_info":0,"uagb_excerpt":"Fork & Bottle was born in 2012 from a love of craft beer, gastro-pub cuisine, and community.","_links":{"self":[{"href":"https:\/\/nodengo.com\/pt\/wp-json\/wp\/v2\/citadela-item\/9091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nodengo.com\/pt\/wp-json\/wp\/v2\/citadela-item"}],"about":[{"href":"https:\/\/nodengo.com\/pt\/wp-json\/wp\/v2\/types\/citadela-item"}],"author":[{"embeddable":true,"href":"https:\/\/nodengo.com\/pt\/wp-json\/wp\/v2\/users\/249"}],"replies":[{"embeddable":true,"href":"https:\/\/nodengo.com\/pt\/wp-json\/wp\/v2\/comments?post=9091"}],"version-history":[{"count":0,"href":"https:\/\/nodengo.com\/pt\/wp-json\/wp\/v2\/citadela-item\/9091\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nodengo.com\/pt\/wp-json\/wp\/v2\/media\/9092"}],"wp:attachment":[{"href":"https:\/\/nodengo.com\/pt\/wp-json\/wp\/v2\/media?parent=9091"}],"wp:term":[{"taxonomy":"citadela-item-category","embeddable":true,"href":"https:\/\/nodengo.com\/pt\/wp-json\/wp\/v2\/citadela-item-category?post=9091"},{"taxonomy":"citadela-item-location","embeddable":true,"href":"https:\/\/nodengo.com\/pt\/wp-json\/wp\/v2\/citadela-item-location?post=9091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}