{"id":9652,"date":"2021-05-05T16:37:53","date_gmt":"2021-05-05T14:37:53","guid":{"rendered":"https:\/\/nodengo.com\/?post_type=citadela-item&#038;p=9652"},"modified":"2023-10-23T23:41:59","modified_gmt":"2023-10-23T21:41:59","slug":"toy-museum","status":"publish","type":"citadela-item","link":"https:\/\/nodengo.com\/es\/item\/toy-museum\/","title":{"rendered":"Museo del Juguete"},"content":{"rendered":"<p><img decoding=\"async\" data-src=\"https:\/\/nodengo.com\/wp-content\/uploads\/bbjlogo22.gif\" alt=\"Museo del Juguete\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 58px; --smush-placeholder-aspect-ratio: 58\/57;\"><\/p>\n<h4>Museo del Juguete<\/h4>\n<\/p>\n<p>\u00a1Peque\u00f1o pero bonito!<br \/>\nThis collection of European toys from the 18th to the middle of the 20th century can be found in one of the oldest corners of Zurich&#8217;s old town.<\/p>\n<p>Juguetes que reflejan la vida de la \u00e9poca respectiva en miniatura: los ferrocarriles y las m\u00e1quinas de vapor son testigos de la revoluci\u00f3n t\u00e9cnica, las mu\u00f1ecas y su ropa muestran tendencias de moda, las casas de mu\u00f1ecas muestran la vida dom\u00e9stica de \u00e9pocas anteriores. Figuras de peltre, juegos antiguos, juguetes de madera, libros para ni\u00f1os y estufas: todo lo relacionado con los juguetes se puede encontrar en este museo.<\/p>\n<p>Hay una zona de juegos para ni\u00f1os. La tarifa de admisi\u00f3n est\u00e1 incluida en la tarjeta de la ciudad. <a href=\"https:\/\/nodengo.com\/es\/item\/zurich-card\/\"><strong>Z\u00fcrich Card<\/strong><\/a>. Ni\u00f1os hasta 16 a\u00f1os gratis.<\/p>\n<p><i class=\"fas fa-map-signs\"><\/i> M\u00e1s tours y actividades en <a href=\"https:\/\/nodengo.com\/es\/zurich\/activities-in-zurich\/\"><strong>Z\u00farich<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Toy museum &#8211; Has a collection of European toys from the 18th to the middle of the 20th century<\/p>","protected":false},"author":249,"featured_media":9653,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","citadela-item-category":[409,338],"citadela-item-location":[390],"class_list":["post-9652","citadela-item","type-citadela-item","status-publish","has-post-thumbnail","hentry","citadela-item-category-kid-stuff","citadela-item-category-museum","citadela-item-location-zurich"],"uagb_featured_image_src":{"full":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich.jpg",380,285,false],"thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich-150x150.jpg",150,150,true],"medium":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich-300x225.jpg",300,225,true],"medium_large":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich.jpg",380,285,false],"large":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich.jpg",380,285,false],"1536x1536":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich.jpg",380,285,false],"2048x2048":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich.jpg",380,285,false],"trp-custom-language-flag":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich-16x12.jpg",16,12,true],"citadela_item_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich.jpg",380,285,false],"woocommerce_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich.jpg",380,285,false],"woocommerce_single":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich.jpg",380,285,false],"woocommerce_gallery_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich-150x113.jpg",150,113,true],"citadela_service":["https:\/\/nodengo.com\/wp-content\/uploads\/toymuseumzurich.jpg",380,285,false]},"uagb_author_info":{"display_name":"Team Nodengo","author_link":"https:\/\/nodengo.com\/es\/author\/nodengo-team\/"},"uagb_comment_info":0,"uagb_excerpt":"Toy museum - Has a collection of European toys from the 18th to the middle of the 20th century","_links":{"self":[{"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/citadela-item\/9652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/citadela-item"}],"about":[{"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/types\/citadela-item"}],"author":[{"embeddable":true,"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/users\/249"}],"replies":[{"embeddable":true,"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/comments?post=9652"}],"version-history":[{"count":0,"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/citadela-item\/9652\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/media\/9653"}],"wp:attachment":[{"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/media?parent=9652"}],"wp:term":[{"taxonomy":"citadela-item-category","embeddable":true,"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/citadela-item-category?post=9652"},{"taxonomy":"citadela-item-location","embeddable":true,"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/citadela-item-location?post=9652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}