{"id":9067,"date":"2021-04-27T11:43:26","date_gmt":"2021-04-27T09:43:26","guid":{"rendered":"https:\/\/nodengo.com\/?post_type=citadela-item&#038;p=9067"},"modified":"2023-10-15T14:02:37","modified_gmt":"2023-10-15T12:02:37","slug":"chalet-des-bains","status":"publish","type":"citadela-item","link":"https:\/\/nodengo.com\/es\/item\/chalet-des-bains\/","title":{"rendered":"Chalet des Bains"},"content":{"rendered":"<p><img decoding=\"async\" data-src=\"https:\/\/nodengo.com\/wp-content\/uploads\/bbjlogo22.gif\" alt=\"Chalet des Bains\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 58px; --smush-placeholder-aspect-ratio: 58\/57;\">\u00a0 <\/p>\n<h4>Chalet des Bains<\/h4>\n<p>En junio de 2017, Natascha y Alain Kallenbach se hicieron cargo del Chalet des Bains en Vidy, Lausana.<br \/>\nCon el deseo de mantener un ambiente amistoso y cordial, el equipo de Chalet des Bains se esfuerza por cuidar a sus clientes, darles la bienvenida y atenderlos de una manera relajada pero profesional.<\/p>\n<p>Activos en el campo de la restauraci\u00f3n, los eventos y la restauraci\u00f3n desde hace m\u00e1s de 20 a\u00f1os, Natascha y Alain abogan por la convivencia y el buen comer sin dejar de ser accesibles para todos.<\/p>\n<p>Le Chalet des Bains tiene una gran terraza y una gran sala para sus seminarios y eventos privados.<\/p>\n<p><i class=\"fas fa-utensils\"><\/i><a href=\"https:\/\/nodengo.com\/es\/lausanne\/lausanne-restaurants\/\">   M\u00c1S RESTAURANTES DE LAUSANA<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>\u00a0 Chalet des Bains It was in June 2017 that Natascha and Alain Kallenbach took over the Chalet des Bains in Vidy, Lausanne. Wanting to maintain a friendly and convivial [&hellip;]<\/p>\n","protected":false},"author":249,"featured_media":8567,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","citadela-item-category":[334],"citadela-item-location":[395],"class_list":["post-9067","citadela-item","type-citadela-item","status-publish","has-post-thumbnail","hentry","citadela-item-category-restaurant","citadela-item-location-lausanne"],"uagb_featured_image_src":{"full":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1.jpg",500,375,false],"thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1-150x150.jpg",150,150,true],"medium":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1-300x225.jpg",300,225,true],"medium_large":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1.jpg",500,375,false],"large":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1.jpg",500,375,false],"1536x1536":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1.jpg",500,375,false],"2048x2048":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1.jpg",500,375,false],"trp-custom-language-flag":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1-16x12.jpg",16,12,true],"citadela_item_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1.jpg",500,375,false],"woocommerce_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1.jpg",500,375,false],"woocommerce_single":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1.jpg",500,375,false],"woocommerce_gallery_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1-150x113.jpg",150,113,true],"citadela_service":["https:\/\/nodengo.com\/wp-content\/uploads\/blog-no-img-1-480x360.jpg",480,360,true]},"uagb_author_info":{"display_name":"Team Nodengo","author_link":"https:\/\/nodengo.com\/es\/author\/nodengo-team\/"},"uagb_comment_info":0,"uagb_excerpt":"\u00a0 Chalet des Bains It was in June 2017 that Natascha and Alain Kallenbach took over the Chalet des Bains in Vidy, Lausanne. Wanting to maintain a friendly and convivial [&hellip;]","_links":{"self":[{"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/citadela-item\/9067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/citadela-item"}],"about":[{"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/types\/citadela-item"}],"author":[{"embeddable":true,"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/users\/249"}],"replies":[{"embeddable":true,"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/comments?post=9067"}],"version-history":[{"count":0,"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/citadela-item\/9067\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/media\/8567"}],"wp:attachment":[{"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/media?parent=9067"}],"wp:term":[{"taxonomy":"citadela-item-category","embeddable":true,"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/citadela-item-category?post=9067"},{"taxonomy":"citadela-item-location","embeddable":true,"href":"https:\/\/nodengo.com\/es\/wp-json\/wp\/v2\/citadela-item-location?post=9067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}