{"id":9273,"date":"2021-04-28T18:01:29","date_gmt":"2021-04-28T16:01:29","guid":{"rendered":"https:\/\/nodengo.com\/?post_type=citadela-item&#038;p=9273"},"modified":"2026-01-07T17:34:28","modified_gmt":"2026-01-07T16:34:28","slug":"the-dolder-grand-restaurant","status":"publish","type":"citadela-item","link":"https:\/\/nodengo.com\/de\/item\/the-dolder-grand-restaurant\/","title":{"rendered":"The Dolder Grand Restaurant"},"content":{"rendered":"<p><img decoding=\"async\" data-src=\"https:\/\/nodengo.com\/wp-content\/uploads\/bbjlogo22.gif\" alt=\"The Dolder Grand Restaurant\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 58px; --smush-placeholder-aspect-ratio: 58\/57;\">\u00a0 <\/p>\n<h4>The Dolder Grand Restaurant<\/h4>\n<\/p>\n<p>Das Restaurant serviert frische und innovative Gourmetk\u00fcche kreiert von unserem Chef Fine Dining Heiko Nieder in stilvollem Ambiente. Das Gourmetrestaurant ist mit 19 GaultMillau-Punkten und 2 Michelin-Sternen ausgezeichnet und z\u00e4hlt zu den am h\u00f6chsten bewerteten Restaurants in Z\u00fcrich. Kommen Sie und probieren Sie eine \u00fcberraschende und scheinbar endlose Vielfalt an Geschmacksrichtungen und genie\u00dfen Sie einen unvergesslichen Abend im Michelin-Restaurant.\n<\/p>\n<\/p>\n<p>GESCHMACKSPREIS VON HEIKO NIEDER<br \/>\nUnser K\u00fcchenchef Fine Dining Heiko Nieder pr\u00e4sentiert eine Reihe faszinierender Gerichte, die klassische kulinarische Vorurteile \u00fcberwinden. F\u00fcr seine Kreationen im In- und Ausland, die sich durch ihre beeindruckende Geschmacksvielfalt auszeichnen, wurde er mehrfach ausgezeichnet. Sein Gourmetrestaurant hat aktuell 2 Michein-Sterne und 19 Gault Millau-Punkte.<\/p>\n<p>Das Restaurant beherbergt einen stilvoll eingerichteten Private Dining Room, der f\u00fcr Feiern mit bis zu 12 Personen zur Verf\u00fcgung steht. F\u00fcr Gruppen ab sechs Personen stellt unser Chef Fine Dining, Heiko Nieder, ein Men\u00fc speziell f\u00fcr Sie zusammen.<\/p>\n<p><i class=\"fas fa-bed\"><\/i>Das Restaurant befindet sich im exklusiven <a href=\"https:\/\/expedia.tpx.gr\/PAT86m6t\" target=\"_blank\" rel=\"noopener\"><strong>The Dolder Grand Hotel<\/strong><\/a><\/p>\n<p><i class=\"fas fa-utensils\"><\/i><a href=\"https:\/\/nodengo.com\/de\/zurich\/zurich-restaurants\/\">WEITERE RESTAURANTS IN Z\u00dcRICH<\/a> <\/p>","protected":false},"excerpt":{"rendered":"<p>The Dolder Grand Restaurant &#8211; Our Chef Fine Dining Heiko Nieder presents an array of intriguing dishes that defy classic culinary preconceptions<\/p>","protected":false},"author":249,"featured_media":9274,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","citadela-item-category":[471,334],"citadela-item-location":[390],"class_list":["post-9273","citadela-item","type-citadela-item","status-publish","has-post-thumbnail","hentry","citadela-item-category-formal","citadela-item-category-restaurant","citadela-item-location-zurich"],"uagb_featured_image_src":{"full":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich.jpg",507,321,false],"thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich-150x150.jpg",150,150,true],"medium":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich-300x190.jpg",300,190,true],"medium_large":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich.jpg",507,321,false],"large":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich.jpg",507,321,false],"1536x1536":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich.jpg",507,321,false],"2048x2048":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich.jpg",507,321,false],"trp-custom-language-flag":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich-16x10.jpg",16,10,true],"citadela_item_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich.jpg",507,321,false],"woocommerce_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich.jpg",507,321,false],"woocommerce_single":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich.jpg",507,321,false],"woocommerce_gallery_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich-150x95.jpg",150,95,true],"citadela_service":["https:\/\/nodengo.com\/wp-content\/uploads\/dodlergrandzurich-480x321.jpg",480,321,true]},"uagb_author_info":{"display_name":"Team Nodengo","author_link":"https:\/\/nodengo.com\/de\/author\/nodengo-team\/"},"uagb_comment_info":0,"uagb_excerpt":"The Dolder Grand Restaurant - Our Chef Fine Dining Heiko Nieder presents an array of intriguing dishes that defy classic culinary preconceptions","_links":{"self":[{"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/citadela-item\/9273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/citadela-item"}],"about":[{"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/types\/citadela-item"}],"author":[{"embeddable":true,"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/users\/249"}],"replies":[{"embeddable":true,"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/comments?post=9273"}],"version-history":[{"count":0,"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/citadela-item\/9273\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/media\/9274"}],"wp:attachment":[{"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/media?parent=9273"}],"wp:term":[{"taxonomy":"citadela-item-category","embeddable":true,"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/citadela-item-category?post=9273"},{"taxonomy":"citadela-item-location","embeddable":true,"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/citadela-item-location?post=9273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}