{"id":7603,"date":"2021-03-25T08:38:17","date_gmt":"2021-03-25T07:38:17","guid":{"rendered":"https:\/\/nodengo.com\/?post_type=citadela-item&#038;p=7603"},"modified":"2026-08-24T13:21:24","modified_gmt":"2026-08-24T11:21:24","slug":"le-cafe-des-sources","status":"publish","type":"citadela-item","link":"https:\/\/nodengo.com\/de\/item\/le-cafe-des-sources\/","title":{"rendered":"Le Caf\u00e9 des Sources"},"content":{"rendered":"<p><img decoding=\"async\" data-src=\"https:\/\/nodengo.com\/wp-content\/uploads\/bbjlogo22.gif\" alt=\"Le Caf\u00e9 des Sources \" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 58px; --smush-placeholder-aspect-ratio: 58\/57;\"><\/p>\n<h4>Le Caf\u00e9 des Sources<\/h4>\n<p>Unsere saisonale K\u00fcche pr\u00e4sentiert frische, regionale und saisonale Produkte, die sorgf\u00e4ltig ausgew\u00e4hlt werden, um ihren vollen Geschmack zu bewahren. Jedes Gericht spiegelt unser Engagement f\u00fcr authentische, ehrliche K\u00fcche wider, in der Hausgemachtes seine volle Bedeutung erh\u00e4lt.<\/p>\n<p>Im Caf\u00e9 des Sources schaffen wir Emotionen durch Gerichte, die Menschen zusammenbringen. Hier treffen Geselligkeit und Gastfreundschaft in einer herzlichen, unpr\u00e4tenti\u00f6sen Atmosph\u00e4re aufeinander, in der die G\u00e4ste in erster Linie gutes Essen genie\u00dfen und einen authentischen Moment teilen m\u00f6chten.<\/p>\n<p><i class=\"fas fa-utensils\"><\/i><a href=\"https:\/\/nodengo.com\/de\/switzerland\/geneva\/geneva-restaurants\/\">  MEHR GENF RESTAURANTS<\/a> <\/p>","protected":false},"excerpt":{"rendered":"<p>Le Caf\u00e9 des Sources Gen\u00e8ve ist eine gute Nachbarschaftsadresse, ein h\u00fcbsches Bistro, das hochwertige Gastronomie bietet.<\/p>","protected":false},"author":249,"featured_media":7605,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","citadela-item-category":[334],"citadela-item-location":[325],"class_list":["post-7603","citadela-item","type-citadela-item","status-publish","has-post-thumbnail","hentry","citadela-item-category-restaurant","citadela-item-location-geneva"],"uagb_featured_image_src":{"full":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva.jpg",461,307,false],"thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva-150x150.jpg",150,150,true],"medium":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva-300x200.jpg",300,200,true],"medium_large":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva.jpg",461,307,false],"large":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva.jpg",461,307,false],"1536x1536":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva.jpg",461,307,false],"2048x2048":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva.jpg",461,307,false],"trp-custom-language-flag":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva-16x12.jpg",16,12,true],"citadela_item_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva.jpg",461,307,false],"woocommerce_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva.jpg",461,307,false],"woocommerce_single":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva.jpg",461,307,false],"woocommerce_gallery_thumbnail":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva-150x100.jpg",150,100,true],"citadela_service":["https:\/\/nodengo.com\/wp-content\/uploads\/cafedesourcesgva.jpg",461,307,false]},"uagb_author_info":{"display_name":"Team Nodengo","author_link":"https:\/\/nodengo.com\/de\/author\/nodengo-team\/"},"uagb_comment_info":0,"uagb_excerpt":"Le Caf\u00e9 des Sources Gen\u00e8ve is a good neighborhood address, a pretty bistro that offers quality catering.","_links":{"self":[{"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/citadela-item\/7603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/citadela-item"}],"about":[{"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/types\/citadela-item"}],"author":[{"embeddable":true,"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/users\/249"}],"replies":[{"embeddable":true,"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/comments?post=7603"}],"version-history":[{"count":0,"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/citadela-item\/7603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/media\/7605"}],"wp:attachment":[{"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/media?parent=7603"}],"wp:term":[{"taxonomy":"citadela-item-category","embeddable":true,"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/citadela-item-category?post=7603"},{"taxonomy":"citadela-item-location","embeddable":true,"href":"https:\/\/nodengo.com\/de\/wp-json\/wp\/v2\/citadela-item-location?post=7603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}